{"id":92039,"date":"2026-04-18T18:01:40","date_gmt":"2026-04-18T16:01:40","guid":{"rendered":"https:\/\/somllavors.com\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba"},"modified":"2026-04-18T18:01:40","modified_gmt":"2026-04-18T16:01:40","slug":"gafas-de-sol-4-6-anos-square-verd-salvia-beaba","status":"publish","type":"product","link":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba","title":{"rendered":"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba"},"content":{"rendered":"<h2 data-path-to-node=\"5\">Gafas de sol (4-6 a\u00f1os): B\u00e9aba Square Color Verde Salvia<\/h2>\n<p data-path-to-node=\"6\">En la etapa de 4 a 6 a\u00f1os, las criaturas tienen una autonom\u00eda enorme y disfrutan de juegos mucho m\u00e1s din\u00e1micos en el exterior. Para garantizar que su salud visual est\u00e9 protegida sin renunciar a la comodidad, B\u00e9aba ha dise\u00f1ado las gafas Square Sunny con ayuda de profesionales m\u00e9dicos (\u00f3pticos, oftalm\u00f3logos y oste\u00f3patas). Este modelo, en un bonito y natural tono verde salvia, es el equilibrio perfecto entre tecnolog\u00eda, protecci\u00f3n y estilo contempor\u00e1neo.  <\/p>\n<h3 data-path-to-node=\"7\">Caracter\u00edsticas t\u00e9cnicas destacadas:<\/h3>\n<ul data-path-to-node=\"8\">\n<li>\n<p data-path-to-node=\"8,0,0\">Lentes de Categor\u00eda 3 (100% UV): Ofrecen una barrera total contra los rayos UVA, UVB y UVC. Son ideales para entornos de fuerte luminosidad o reverberaci\u00f3n, cuidando la vista durante largas exposiciones. <\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,1,0\">Confort absoluto &#8220;Fit Tech&#8221;: La zona de la nariz, las sienes y el interior de las patillas est\u00e1n recubiertos con el material suave Fit Tech. Esto, sumado a las bisagras flexibles, evita cualquier tipo de compresi\u00f3n o marca en el rostro. <\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,2,0\">Ajuste a medida (360\u00b0): Las puntas de las patillas se pueden curvar y ajustar en cualquier direcci\u00f3n. Se adaptan exactamente a la forma de la oreja de cada ni\u00f1o, garantizando que no caigan ni molesten y evolucionando con su crecimiento. <\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,3,0\">Sistema &#8220;Clip &amp; Play&#8221;: Incorpora un pr\u00e1ctico cord\u00f3n el\u00e1stico ajustable que se engancha f\u00e1cilmente a las patillas, ideal para asegurar las gafas durante los juegos m\u00e1s movidos o las actividades deportivas.<\/p>\n<\/li>\n<\/ul>\n<h3 data-path-to-node=\"9\">\u00bfPor qu\u00e9 elegir este modelo?<\/h3>\n<p data-path-to-node=\"10\">Son, sin duda, las gafas que no querr\u00e1n quitarse. Gracias al estudio anat\u00f3mico que se encuentra detr\u00e1s de su dise\u00f1o, ofrecen una sensaci\u00f3n de libertad total. Son ultra-resistentes y est\u00e1n preparadas para aguantar el ritmo incansable de esa edad. El color verde salvia es moderno, neutro y conecta directamente con la naturaleza, siendo un complemento fant\u00e1stico y muy vers\u00e1til para el d\u00eda a d\u00eda.   <\/p>\n<blockquote data-path-to-node=\"11\">\n<p data-path-to-node=\"11,0\">El consejo de Som Llavors: \u00a1El tono verde salvia es ideal para las escapadas a la monta\u00f1a o al bosque! Recuerde aprovechar su pr\u00e1ctico sistema &#8220;clip &amp; play&#8221; para pegar la cinta el\u00e1stica cuando planifique actividades de mayor movimiento, como montar en bicicleta, en patinete o hacer excursiones, garantizando que las gafas estar\u00e1n siempre a salvo de ca\u00eddas accidentales. <\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p data-path-to-node=\"1\"><b data-path-to-node=\"1\" data-index-in-node=\"0\">Gafas de sol B\u00e9aba Square Verd Salvia: M\u00e1xima protecci\u00f3n y dise\u00f1o experto para la etapa m\u00e1s activa (4-6 a\u00f1os)<\/b><\/p>\n<p data-path-to-node=\"2\">Unas gafas de sol innovadoras, dise\u00f1adas en colaboraci\u00f3n con \u00f3pticos, oftalm\u00f3logos y oste\u00f3patas, para ofrecer el m\u00e1ximo confort y seguridad a las criaturas de 4 a 6 a\u00f1os con un fresco y natural toque verde salvia.<\/p>\n<ul data-path-to-node=\"3\">\n<li>\n<p data-path-to-node=\"3,0,0\">Protecci\u00f3n UV Categor\u00eda 3: Lentes que filtran el 100% de los rayos solares, proporcionando una seguridad \u00f3ptima tanto en la playa como en la monta\u00f1a.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"3,1,0\">Ergonom\u00eda &#8220;Fit Tech&#8221; y ajustable: Bisagras flexibles y extremos de las patillas ajustables a 360\u00b0 para que se adapten al o\u00eddo sin generar ning\u00fan punto de presi\u00f3n.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"3,2,0\">Sujeci\u00f3n y accesorios: Incluyen una cinta el\u00e1stica con sistema &#8220;clip&amp;play&#8221; anti-p\u00e9rdida, adem\u00e1s de un estuche r\u00edgido y una funda de microfibra.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"featured_media":91621,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"pwb-brand":[4285],"product_brand":[],"product_cat":[3627],"product_tag":[5885,5559],"class_list":{"0":"post-92039","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-beaba","7":"product_cat-gafas-de-sol","8":"product_tag-beaba","9":"product_tag-gafas-de-sol-es-2","10":"desktop-align-left","11":"tablet-align-left","12":"mobile-align-left","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba &#8212; Som Llavors<\/title>\n<meta name=\"description\" content=\"Gafas de sol B\u00e9aba Square Verd Salvia: M\u00e1xima protecci\u00f3n y dise\u00f1o experto para la etapa m\u00e1s activa (4-6 a\u00f1os) Unas gafas de sol innovadoras, dise\u00f1adas en colaboraci\u00f3n con \u00f3pticos, oftalm\u00f3logos y oste\u00f3patas, para ofrecer el m\u00e1ximo confort y seguridad a las criaturas de 4 a 6 a\u00f1os con un fresco y natural toque verde salvia.   Protecci\u00f3n UV Categor\u00eda 3: Lentes que filtran el 100% de los rayos solares, proporcionando una seguridad \u00f3ptima tanto en la playa como en la monta\u00f1a.   Ergonom\u00eda &quot;Fit Tech&quot; y ajustable: Bisagras flexibles y extremos de las patillas ajustables a 360\u00b0 para que se adapten al o\u00eddo sin generar ning\u00fan punto de presi\u00f3n.   Sujeci\u00f3n y accesorios: Incluyen una cinta el\u00e1stica con sistema &quot;clip&amp;play&quot; anti-p\u00e9rdida, adem\u00e1s de un estuche r\u00edgido y una funda de microfibra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba\" \/>\n<meta property=\"og:description\" content=\"La teva botiga d\u2019ecocrian\u00e7a i espai d\u2019acompanyament a la maternitat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba\" \/>\n<meta property=\"og:site_name\" content=\"Som Llavors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/somllavorsvng\/?locale=ca_ES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somllavors.com\/wp-content\/uploads\/2026\/04\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Precio\" \/>\n\t<meta name=\"twitter:data1\" content=\"35,00&euro; Iva incl\u00f2s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Hay existencias\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba\",\"url\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba\",\"name\":\"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba &#8212; Som Llavors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somllavors.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg\",\"datePublished\":\"2026-04-18T16:01:40+00:00\",\"description\":\"Gafas de sol B\u00e9aba Square Verd Salvia: M\u00e1xima protecci\u00f3n y dise\u00f1o experto para la etapa m\u00e1s activa (4-6 a\u00f1os) Unas gafas de sol innovadoras, dise\u00f1adas en colaboraci\u00f3n con \u00f3pticos, oftalm\u00f3logos y oste\u00f3patas, para ofrecer el m\u00e1ximo confort y seguridad a las criaturas de 4 a 6 a\u00f1os con un fresco y natural toque verde salvia. Protecci\u00f3n UV Categor\u00eda 3: Lentes que filtran el 100% de los rayos solares, proporcionando una seguridad \u00f3ptima tanto en la playa como en la monta\u00f1a. Ergonom\u00eda \\\"Fit Tech\\\" y ajustable: Bisagras flexibles y extremos de las patillas ajustables a 360\u00b0 para que se adapten al o\u00eddo sin generar ning\u00fan punto de presi\u00f3n. Sujeci\u00f3n y accesorios: Incluyen una cinta el\u00e1stica con sistema \\\"clip&amp;play\\\" anti-p\u00e9rdida, adem\u00e1s de un estuche r\u00edgido y una funda de microfibra.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#primaryimage\",\"url\":\"https:\\\/\\\/somllavors.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg\",\"contentUrl\":\"https:\\\/\\\/somllavors.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg\",\"width\":800,\"height\":800,\"caption\":\"ulleres de sol beaba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/somllavors.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/somllavors.com\\\/es\\\/botiga-2\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somllavors.com\\\/es#website\",\"url\":\"https:\\\/\\\/somllavors.com\\\/es\",\"name\":\"Som Llavors\",\"description\":\"Botiga de crian\u00e7a natural\",\"publisher\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es#organization\"},\"alternateName\":\"Crian\u00e7a Natural i Sostenible\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somllavors.com\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\",\"Store\"],\"@id\":\"https:\\\/\\\/somllavors.com\\\/es#organization\",\"name\":\"Som Llavors\",\"alternateName\":\"Crian\u00e7a Natural i Sostenible\",\"url\":\"https:\\\/\\\/somllavors.com\\\/es\",\"logo\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/somllavorsvng\\\/?locale=ca_ES\",\"https:\\\/\\\/www.instagram.com\\\/somllavors_vng\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@somllavors\"],\"address\":{\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"41.2257737\",\"longitude\":\"1.723258859\"},\"telephone\":[\"623152704\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"00:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\"],\"opens\":\"10:00\",\"closes\":\"20:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Saturday\"],\"opens\":\"10:00\",\"closes\":\"13:30\"}],\"email\":\"info@somllavors.com\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-place-address\",\"streetAddress\":\"Carrer de l'aigua, 6\",\"addressLocality\":\"Vilanova i la Geltr\u00fa\",\"postalCode\":\"08800\",\"addressRegion\":\"Barcelona\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somllavors.com\\\/es\\\/producte\\\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-organization-logo\",\"url\":\"https:\\\/\\\/somllavors.com\\\/wp-content\\\/uploads\\\/Logotip-Som-Llavors.jpg\",\"contentUrl\":\"https:\\\/\\\/somllavors.com\\\/wp-content\\\/uploads\\\/Logotip-Som-Llavors.jpg\",\"width\":1444,\"height\":1323,\"caption\":\"Som Llavors\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"35.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"930425\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Vilanova i la Geltr\u00fa\" \/>\n<meta name=\"geo.position\" content=\"41.2257737;1.723258859\" \/>\n<meta name=\"geo.region\" content=\"Espa\u00f1a\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba &#8212; Som Llavors","description":"Gafas de sol B\u00e9aba Square Verd Salvia: M\u00e1xima protecci\u00f3n y dise\u00f1o experto para la etapa m\u00e1s activa (4-6 a\u00f1os) Unas gafas de sol innovadoras, dise\u00f1adas en colaboraci\u00f3n con \u00f3pticos, oftalm\u00f3logos y oste\u00f3patas, para ofrecer el m\u00e1ximo confort y seguridad a las criaturas de 4 a 6 a\u00f1os con un fresco y natural toque verde salvia.   Protecci\u00f3n UV Categor\u00eda 3: Lentes que filtran el 100% de los rayos solares, proporcionando una seguridad \u00f3ptima tanto en la playa como en la monta\u00f1a.   Ergonom\u00eda \"Fit Tech\" y ajustable: Bisagras flexibles y extremos de las patillas ajustables a 360\u00b0 para que se adapten al o\u00eddo sin generar ning\u00fan punto de presi\u00f3n.   Sujeci\u00f3n y accesorios: Incluyen una cinta el\u00e1stica con sistema \"clip&amp;play\" anti-p\u00e9rdida, adem\u00e1s de un estuche r\u00edgido y una funda de microfibra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba","og_locale":"es_ES","og_type":"article","og_title":"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba","og_description":"La teva botiga d\u2019ecocrian\u00e7a i espai d\u2019acompanyament a la maternitat","og_url":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba","og_site_name":"Som Llavors","article_publisher":"https:\/\/www.facebook.com\/somllavorsvng\/?locale=ca_ES","og_image":[{"width":800,"height":800,"url":"https:\/\/somllavors.com\/wp-content\/uploads\/2026\/04\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Precio":"35,00&euro; Iva incl\u00f2s","Availability":"Hay existencias"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba","url":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba","name":"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba &#8212; Som Llavors","isPartOf":{"@id":"https:\/\/somllavors.com\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#primaryimage"},"image":{"@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#primaryimage"},"thumbnailUrl":"https:\/\/somllavors.com\/wp-content\/uploads\/2026\/04\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg","datePublished":"2026-04-18T16:01:40+00:00","description":"Gafas de sol B\u00e9aba Square Verd Salvia: M\u00e1xima protecci\u00f3n y dise\u00f1o experto para la etapa m\u00e1s activa (4-6 a\u00f1os) Unas gafas de sol innovadoras, dise\u00f1adas en colaboraci\u00f3n con \u00f3pticos, oftalm\u00f3logos y oste\u00f3patas, para ofrecer el m\u00e1ximo confort y seguridad a las criaturas de 4 a 6 a\u00f1os con un fresco y natural toque verde salvia. Protecci\u00f3n UV Categor\u00eda 3: Lentes que filtran el 100% de los rayos solares, proporcionando una seguridad \u00f3ptima tanto en la playa como en la monta\u00f1a. Ergonom\u00eda \"Fit Tech\" y ajustable: Bisagras flexibles y extremos de las patillas ajustables a 360\u00b0 para que se adapten al o\u00eddo sin generar ning\u00fan punto de presi\u00f3n. Sujeci\u00f3n y accesorios: Incluyen una cinta el\u00e1stica con sistema \"clip&amp;play\" anti-p\u00e9rdida, adem\u00e1s de un estuche r\u00edgido y una funda de microfibra.","breadcrumb":{"@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#primaryimage","url":"https:\/\/somllavors.com\/wp-content\/uploads\/2026\/04\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg","contentUrl":"https:\/\/somllavors.com\/wp-content\/uploads\/2026\/04\/Som-Llavors-Gafas-de-sol-4-6-anos-SQUARE-SUNNY-Verde-Salvia-930425_product_3-4_1.jpg","width":800,"height":800,"caption":"ulleres de sol beaba"},{"@type":"BreadcrumbList","@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/somllavors.com\/es"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/somllavors.com\/es\/botiga-2"},{"@type":"ListItem","position":3,"name":"Gafas de sol 4-6 a\u00f1os Square Verd Salvia \u2013 B\u00e9aba"}]},{"@type":"WebSite","@id":"https:\/\/somllavors.com\/es#website","url":"https:\/\/somllavors.com\/es","name":"Som Llavors","description":"Botiga de crian\u00e7a natural","publisher":{"@id":"https:\/\/somllavors.com\/es#organization"},"alternateName":"Crian\u00e7a Natural i Sostenible","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somllavors.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place","Store"],"@id":"https:\/\/somllavors.com\/es#organization","name":"Som Llavors","alternateName":"Crian\u00e7a Natural i Sostenible","url":"https:\/\/somllavors.com\/es","logo":{"@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-organization-logo"},"image":{"@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/somllavorsvng\/?locale=ca_ES","https:\/\/www.instagram.com\/somllavors_vng\/","https:\/\/www.youtube.com\/@somllavors"],"address":{"@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"41.2257737","longitude":"1.723258859"},"telephone":["623152704","623152704"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Sunday"],"opens":"00:00","closes":"00:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Tuesday","Wednesday","Thursday","Friday"],"opens":"10:00","closes":"20:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Saturday"],"opens":"10:00","closes":"13:30"}],"email":"info@somllavors.com"},{"@type":"PostalAddress","@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-place-address","streetAddress":"Carrer de l'aigua, 6","addressLocality":"Vilanova i la Geltr\u00fa","postalCode":"08800","addressRegion":"Barcelona","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somllavors.com\/es\/producte\/gafas-de-sol-4-6-anos-square-verd-salvia-beaba#local-main-organization-logo","url":"https:\/\/somllavors.com\/wp-content\/uploads\/Logotip-Som-Llavors.jpg","contentUrl":"https:\/\/somllavors.com\/wp-content\/uploads\/Logotip-Som-Llavors.jpg","width":1444,"height":1323,"caption":"Som Llavors"}]},"product_price_amount":"35.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"930425","product_condition":"new","geo.placename":"Vilanova i la Geltr\u00fa","geo.position":{"lat":"41.2257737","long":"1.723258859"},"geo.region":"Espa\u00f1a"},"brands":[{"id":4285,"name":"B\u00e9aba","slug":"beaba"}],"_links":{"self":[{"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/product\/92039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/media\/91621"}],"wp:attachment":[{"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/media?parent=92039"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/pwb-brand?post=92039"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/product_brand?post=92039"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/product_cat?post=92039"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/somllavors.com\/es\/wp-json\/wp\/v2\/product_tag?post=92039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}